{"id":1511,"date":"2022-10-14T14:29:00","date_gmt":"2022-10-14T14:29:00","guid":{"rendered":"https:\/\/54.227.86.48\/?p=1511"},"modified":"2025-03-26T23:42:24","modified_gmt":"2025-03-26T23:42:24","slug":"regularizar-cnpj-mei","status":"publish","type":"post","link":"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei","title":{"rendered":"Regularizar CNPJ MEI: por onde come\u00e7ar e o que fazer?"},"content":{"rendered":"\n<p>Um neg\u00f3cio pequeno deve ser cuidado com tanta aten\u00e7\u00e3o quanto uma grande empresa. Regularizar CNPJ <a href=\"https:\/\/www.companyhero.com\/blog\/o-que-e-mei\">MEI<\/a> sempre que houver uma pend\u00eancia \u00e9 obrigat\u00f3rio para o crescimento do seu neg\u00f3cio. A burocracia para quem atua como Microempreendedor Individual \u00e9 menor, mesmo assim, voc\u00ea precisa ficar de olho para evitar embara\u00e7os.<\/p>\n\n\n\n<p>O controle financeiro do Microempreendedor Individual \u00e9 mais simples, feito com o recolhimento dos impostos em Guia \u00danica. Isso ajuda bastante! Mas, como todos n\u00f3s sabemos, a administra\u00e7\u00e3o de uma empresa tem seus desafios e a inadimpl\u00eancia \u00e9 um problema que assusta empres\u00e1rios de diferentes tamanhos.<\/p>\n\n\n\n<p>Se voc\u00ea trope\u00e7ou pelo caminho e agora quer saber como regularizar CNPJ MEI, pode ficar animado, o processo \u00e9 f\u00e1cil e vamos te contar exatamente o que fazer.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">T\u00f3picos:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei\/#Regularizar_CNPJ_MEI_por_onde_comecar\" >Regularizar CNPJ MEI: por onde come\u00e7ar?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei\/#Por_que_regularizar_CNPJ_MEI\" >Por que regularizar CNPJ MEI?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei\/#Prejuizos_que_podem_surgir_se_voce_nao_regularizar_CNPJ_MEI\" >Preju\u00edzos que podem surgir se voc\u00ea n\u00e3o regularizar CNPJ MEI:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei\/#Qual_e_o_prazo_para_regularizar_CNPJ_MEI\" >Qual \u00e9 o prazo para regularizar CNPJ MEI<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei\/#Como_saber_as_dividas_do_meu_MEI\" >Como saber as d\u00edvidas do meu MEI?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei\/#Qual_e_o_limite_para_emitir_nota_fiscal_no_MEI\" >Qual \u00e9 o limite para emitir nota fiscal no MEI?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.companyhero.com\/blog\/regularizar-cnpj-mei\/#O_que_acha_de_acompanhar_os_processos_do_MEI_com_mais_agilidade\" >O que acha de acompanhar os processos do MEI com mais agilidade?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Regularizar_CNPJ_MEI_por_onde_comecar\"><\/span>Regularizar CNPJ MEI: por onde come\u00e7ar?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Uma empresa que est\u00e1 com a documenta\u00e7\u00e3o em ordem tem mais chances de sucesso no mercado. Isso porque d\u00e1 para acessar linhas de cr\u00e9dito, negociar com fornecedores e investir em marketing sem medo. Se o seu neg\u00f3cio est\u00e1 irregular, tire um tempo na sua agenda para resolver essa quest\u00e3o.<\/p>\n\n\n\n<p>Entre no Portal do Simples Nacional para regularizar CNPJ MEI. Esse \u00e9 o sistema utilizado para a emiss\u00e3o das guias do Documento de Arrecada\u00e7\u00e3o do Simples Nacional (DAS) para pagamento. Voc\u00ea poder\u00e1 analisar os d\u00e9bitos e emitir um DAS com o valor pendente por l\u00e1.<\/p>\n\n\n\n<p>Com a lista de pend\u00eancias em ordem, \u00e9 hora de negociar! A d\u00edvida poder\u00e1 ser parcelada e o CNPJ fica liberado a partir do pagamento e processamento dos d\u00e9bitos. Se suas contas forem mais antigas, anteriores a 2017, fique de olho, pois o Governo Federal enviar\u00e1 esses t\u00edtulos para cobran\u00e7a pela Procuradoria-Geral da Fazenda Nacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Por_que_regularizar_CNPJ_MEI\"><\/span>Por que regularizar CNPJ MEI?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Assim como um CPF com d\u00edvidas traz muitos problemas, uma empresa com d\u00e9bitos fica bastante prejudicada. Al\u00e9m do aumento no valor da quita\u00e7\u00e3o, caso n\u00e3o haja pagamento, existe o risco do CNPJ ser cancelado no futuro. Sendo assim, regularizar CNPJ MEI evita danos ao seu sonho. Voc\u00ea batalhou muito para abrir sua empresa, pense em como seria frustrante colocar tudo a perder.<\/p>\n\n\n\n<p>O lado bom dessa quest\u00e3o burocr\u00e1tica \u00e9 que uma pend\u00eancia de pagamento da Guia \u00danica dentro do ano corrente \u00e9 f\u00e1cil de resolver e n\u00e3o trar\u00e1 grandes preju\u00edzos para o seu neg\u00f3cio. Basta realizar o pagamento para tudo voltar ao normal.<\/p>\n\n\n\n<p>A consequ\u00eancia mais s\u00e9ria acontece quando pend\u00eancias mais antigas, referentes ao pagamento dos impostos simplificados do MEI, forem inscritas na D\u00edvida Ativa da Uni\u00e3o. Nesse caso, o registro no Regime do Simples Nacional pode ser perdido, assim como os benef\u00edcios deste sistema.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Prejuizos_que_podem_surgir_se_voce_nao_regularizar_CNPJ_MEI\"><\/span>Preju\u00edzos que podem surgir se voc\u00ea n\u00e3o regularizar CNPJ MEI:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Entre os principais problemas causados pela irregularidade do documento da empresa est\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Perda de v\u00ednculo com INSS;<\/li>\n\n\n\n<li>Cancelamento dos benef\u00edcios da previd\u00eancia;<\/li>\n\n\n\n<li>Exclus\u00e3o do Simei e do Simples Nacional.<\/li>\n<\/ul>\n\n\n\n<p>Sem o documento de registro da empresa voc\u00ea tamb\u00e9m perder\u00e1 o direito de utilizar as pol\u00edticas do INSS, uma vez que parte da d\u00edvida da cobran\u00e7a unificado do MEI \u00e9 direcionada para isso. \u00c9 melhor resolver tudo o que ficou para tr\u00e1s, n\u00e3o \u00e9?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Qual_e_o_prazo_para_regularizar_CNPJ_MEI\"><\/span>Qual \u00e9 o prazo para regularizar CNPJ MEI<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Seu MEI est\u00e1 irregular, mas voc\u00ea est\u00e1 disposto a resolver isso? \u00c9 necess\u00e1rio agir de acordo com o per\u00edodo no qual ficou devendo os valores de impostos. Tenha o cuidado de descobrir se a empresa j\u00e1 foi penalizada, para ter certeza de que nada fugiu do seu radar.<\/p>\n\n\n\n<p>Existe um prazo final para regulariza\u00e7\u00e3o das pend\u00eancias a cada ano. O per\u00edodo em 2021 ficou estabelecido at\u00e9 30 de setembro. Ele foi prorrogado, pois a data oficial divulgada era 30 de agosto. At\u00e9 o encerramento era poss\u00edvel emitir as guias para pagamento no sistema do Portal do Simples mesmo.<\/p>\n\n\n\n<p>Em 2022, a regulariza\u00e7\u00e3o foi aberta em 29 de abril e conclu\u00edda em 31 de maio. Se voc\u00ea perdeu o prazo para resolver a documenta\u00e7\u00e3o, precisar\u00e1 esperar a divulga\u00e7\u00e3o do per\u00edodo que ser\u00e1 estabelecido em 2023.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_saber_as_dividas_do_meu_MEI\"><\/span>Como saber as d\u00edvidas do meu MEI?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Est\u00e1 desconfiado de que deixou algumas contas para tr\u00e1s? Voc\u00ea pode fazer a consulta desses d\u00e9bitos. Siga os passos a seguir para ver o que est\u00e1 pendente no seu MEI:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>V\u00e1 at\u00e9 o Portal do Simples Nacional;<\/li>\n\n\n\n<li>Entre no Programa Gerador de DAS (PGMEI);<\/li>\n\n\n\n<li>Acesse o menu Consulta Extrato\/Pend\u00eancias;<\/li>\n\n\n\n<li>Emita a guia para pagamento das d\u00edvidas que ainda est\u00e3o com a Receita Federal. Existe a op\u00e7\u00e3o de solicitar o parcelamento dos valores, se preferir.<\/li>\n<\/ul>\n\n\n\n<p>Caso seu valor seja mais antigo e j\u00e1 esteja na D\u00edvida Ativa, o PGMEI apresentar\u00e1 uma mensagem dizendo que a pend\u00eancia mudou de lugar. Nesse caso, \u00e9 preciso emitir um DAS da D\u00edvida Ativa da Uni\u00e3o atrav\u00e9s do portal da Procuradoria-Geral da Fazenda Nacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Qual_e_o_limite_para_emitir_nota_fiscal_no_MEI\"><\/span>Qual \u00e9 o limite para emitir nota fiscal no MEI?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Como voc\u00ea deve saber, o MEI \u00e9 uma categoria simples, mas tamb\u00e9m limitada. O teto de faturamento anual \u00e9 de R$81 mil. Na pr\u00e1tica, voc\u00ea pode emitir uma nota fiscal no valor total, desde que essa seja a \u00fanica cobran\u00e7a da empresa no per\u00edodo de um ano, mas isso \u00e9 raro. O mais comum \u00e9 emitir v\u00e1rias notas que, juntas, chegam ao limite.<\/p>\n\n\n\n<p>Fique atento a um detalhe: o valor de faturamento limite no ano de abertura da empresa \u00e9 contado de acordo com o n\u00famero de meses do ano em que ela estava atuando, considerando R$ 6.750 a cada m\u00eas.<\/p>\n\n\n\n<p>A lei n\u00e3o imp\u00f5e uma regra de bloqueio de emiss\u00e3o de Notas Fiscais para a empresa que ultrapassa o limite de faturamento. A orienta\u00e7\u00e3o \u00e9 que o Microempreendedor Individual solicite o desenquadramento MEI e escolha outro modelo de empresa para seguir atuando no pr\u00f3ximo ano.<\/p>\n\n\n\n<p>Se a sua empresa est\u00e1 aberta como MEI e est\u00e1 se aproximando do limite de R$ 81 mil por ano, consulte outras op\u00e7\u00f5es de enquadramento pelo Simples Nacional. Existem boas alternativas que preservam impostos adequados a uma faixa de faturamento maior, isso \u00e9 \u00f3timo, pois assim voc\u00ea fica livre para investir no crescimento da sua empresa sem medo. Aproveite o potencial de sucesso que ela tem!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_acha_de_acompanhar_os_processos_do_MEI_com_mais_agilidade\"><\/span>O que acha de acompanhar os processos do MEI com mais agilidade?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Um empreendedor precisa cuidar do seu pr\u00f3prio MEI, o que j\u00e1 \u00e9 bem trabalhoso. Agora, imagine a rotina de contadores e advogados que acompanham diferentes empresas? Sabemos que isso pode ser confuso e cansativo, por isso, desenvolvemos uma ferramenta para simplificar o trabalho.<\/p>\n\n\n\n<p>A Plataforma de Legaliza\u00e7\u00e3o permite o gerenciamento dos processos dos clientes, como&nbsp;<a href=\"https:\/\/www.companyhero.com\/blog\/alteracao-contratual\">altera\u00e7\u00e3o contratual<\/a>, regulariza\u00e7\u00e3o CNPJ MEI e emiss\u00e3o de outros documentos com agilidade.<\/p>\n\n\n\n<p><strong>Como funciona a plataforma da Company Hero?<\/strong><\/p>\n\n\n\n<p>Pense nela como uma facilitadora para profissionais da \u00e1rea cont\u00e1bil, inclusive de quem atua com&nbsp;<a href=\"https:\/\/www.companyhero.com\/blog\/servico-paralegal\">servi\u00e7o paralegal<\/a>. Atrav\u00e9s da Plataforma de Legaliza\u00e7\u00e3o, voc\u00ea pode resolver diferentes quest\u00f5es relacionadas \u00e0 documenta\u00e7\u00e3o da empresa, preenchendo formul\u00e1rios sobre a atividade que ser\u00e1 realizada.<\/p>\n\n\n\n<p>Em cada processo aberto voc\u00ea tem o suporte dos especialistas da Hero para te ajudar. Com uma equipe te ajudando no que for necess\u00e1rio, sobra tempo para voc\u00ea lidar com outras quest\u00f5es importantes da empresa, como planejamento fiscal e decis\u00f5es estrat\u00e9gicas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=BUhIxGcNXwk\" target=\"_blank\" rel=\"noopener\">Assista este v\u00eddeo<\/a>\u00a0com tudo o que voc\u00ea precisa saber para aproveitar a plataforma. \u00c9 o que estava faltando na sua rotina de gest\u00e3o de processos!<\/li>\n<\/ul>\n\n\n\n<p>Se voc\u00ea \u00e9 um profissional da \u00e1rea cont\u00e1bil ou advogado, sabe como essa rotina agitada pode ser cansativa. Recorrer \u00e0 Plataforma de Legaliza\u00e7\u00e3o da Company Hero trar\u00e1 muitos benef\u00edcios para suas entregas.<\/p>\n\n\n\n<p>Ficou interessado nessa ferramenta pr\u00e1tica? Fale com a equipe de Heroes e entenda como nossa plataforma de legaliza\u00e7\u00e3o te ajudar\u00e1 a regularizar CNPJ MEI com mais seguran\u00e7a e agilidade. Nossos especialistas est\u00e3o esperando seu contato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Regularizar CNPJ MEI sempre que houver uma pend\u00eancia \u00e9 uma atitude que faz parte do crescimento do seu neg\u00f3cio. Entenda como fazer isso.<\/p>\n","protected":false},"author":4,"featured_media":1512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-1511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-cnpj"],"_links":{"self":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts\/1511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/comments?post=1511"}],"version-history":[{"count":2,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts\/1511\/revisions"}],"predecessor-version":[{"id":2962,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts\/1511\/revisions\/2962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/media\/1512"}],"wp:attachment":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/media?parent=1511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/categories?post=1511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/tags?post=1511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}