{"id":1237,"date":"2024-06-07T20:28:00","date_gmt":"2024-06-07T20:28:00","guid":{"rendered":"https:\/\/54.227.86.48\/?p=1237"},"modified":"2025-05-23T22:13:28","modified_gmt":"2025-05-23T22:13:28","slug":"como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo","status":"publish","type":"post","link":"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo","title":{"rendered":"Como cancelar nota fiscal de servi\u00e7o MEI? Aprenda o passo a passo"},"content":{"rendered":"\n<p>Emitir uma&nbsp;<strong>nota fiscal de servi\u00e7o<\/strong>&nbsp;e perceber que cometeu um engano \u00e9 uma situa\u00e7\u00e3o que acontece com muitos profissionais PJ. Mas n\u00e3o h\u00e1 motivos para preocupa\u00e7\u00e3o: cancelar uma NFS-e sendo <a href=\"https:\/\/www.companyhero.com\/blog\/o-que-e-mei\">MEI<\/a> \u00e9 um processo simples que pode ser realizado em poucos minutos, de forma on-line.<\/p>\n\n\n\n<p>Tudo \u00e9 feito pelo mesmo portal por onde voc\u00ea emitiu a nota. Aprenda&nbsp;<strong>como cancelar nota fiscal de servi\u00e7o MEI<\/strong>&nbsp;no o passo a passo a seguir.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_78 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">T\u00f3picos:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#O_MEI_e_obrigado_a_emitir_nota_fiscal\" >O MEI \u00e9 obrigado a emitir nota fiscal?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#Como_cancelar_uma_nota_fiscal\" >Como cancelar uma nota fiscal?<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#1_%E2%80%93_Acesse_o_site_do_Portal_de_Gestao_NFS-e_e_faca_o_login_com_o_numero_de_CNPJ_e_senha\" >1 &#8211; Acesse o site do&nbsp;Portal de Gest\u00e3o NFS-e&nbsp;e fa\u00e7a o login com o n\u00famero de CNPJ e senha.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#2_%E2%80%93_Apos_o_login_clique_em_%E2%80%9CNFS-e_Emitidas%E2%80%9D_no_canto_superior_direito\" >2 &#8211; Ap\u00f3s o login, clique em \u201cNFS-e Emitidas\u201d, no canto superior direito.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#3_%E2%80%93_Clique_nas_tres_bolinhas_referentes_a_nota_fiscal_que_voce_deseja_cancelar_no_canto_direito_da_tela\" >3 &#8211; Clique nas tr\u00eas bolinhas referentes a nota fiscal que voc\u00ea deseja cancelar, no canto direito da tela.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#4_%E2%80%93_Em_seguida_clique_em_%E2%80%9CCancelar_NFS-e%E2%80%9D\" >4 &#8211; Em seguida, clique em \u201cCancelar NFS-e\u201d.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#5_%E2%80%93_Selecione_a_opcao_referente_ao_motivo_do_cancelamento_e_descreva_a_justificativa\" >5 &#8211; Selecione a op\u00e7\u00e3o referente ao motivo do cancelamento e descreva a justificativa.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.companyhero.com\/blog\/como-cancelar-nota-fiscal-de-servico-mei-aprenda-o-passo-passo\/#6_%E2%80%93_Pronto_a_confirmacao_do_cancelamento_ira_aparecer_na_tela\" >6 &#8211; Pronto, a confirma\u00e7\u00e3o do cancelamento ir\u00e1 aparecer na tela.<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_MEI_e_obrigado_a_emitir_nota_fiscal\"><\/span>O MEI \u00e9 obrigado a emitir nota fiscal?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A&nbsp;<a href=\"https:\/\/www.companyhero.com\/blog\/como-emitir-nota-fiscal-sem-inscricao-estadual\">emiss\u00e3o NFS-e<\/a>&nbsp;\u00e9&nbsp;<strong>obrigat\u00f3ria<\/strong>&nbsp;se o<strong>&nbsp;tomador do<\/strong>&nbsp;<a href=\"https:\/\/www.companyhero.com\/blog\/prestacao-de-servico-como-atuar-com-cnpj\"><strong>servi\u00e7o<\/strong><\/a><strong>&nbsp;for outra empresa<\/strong>&nbsp;(pessoa jur\u00eddica). O MEI n\u00e3o precisa emitir nota fiscal para consumidor pessoa f\u00edsica, exceto quando for solicitado, em atendimento ao C\u00f3digo de Defesa do Consumidor.<\/p>\n\n\n\n<p>Aten\u00e7\u00e3o: o&nbsp;<a href=\"https:\/\/www.companyhero.com\/blog\/documentos-para-abrir-mei\">MEI<\/a>&nbsp;\u00e9 obrigado a emitir suas NFS-e por meio do Portal Nacional desde setembro de 2023.<\/p>\n\n\n\n<p>\ud83d\udc49<a href=\"https:\/\/www.companyhero.com\/blog\/obrigacoes-do-mei\">Leia mais: Obriga\u00e7\u00f5es do MEI: datas anuais que voc\u00ea n\u00e3o pode perder<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_cancelar_uma_nota_fiscal\"><\/span>Como cancelar uma nota fiscal?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Em caso de emiss\u00e3o de uma nota fiscal errada, o&nbsp;<strong>cancelamento \u00e9 feito no<\/strong>&nbsp;<a href=\"https:\/\/www.nfse.gov.br\/EmissorNacional\/Login?ReturnUrl=%2fEmissorNacional\" target=\"_blank\" rel=\"noopener\"><strong>Portal de Gest\u00e3o<\/strong>&nbsp;NFS-e<\/a>, mesma plataforma utilizada para a emiss\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_%E2%80%93_Acesse_o_site_do_Portal_de_Gestao_NFS-e_e_faca_o_login_com_o_numero_de_CNPJ_e_senha\"><\/span>1 &#8211; Acesse o site do&nbsp;<a href=\"https:\/\/www.nfse.gov.br\/EmissorNacional\/Login?ReturnUrl=%2fEmissorNacional\" target=\"_blank\" rel=\"noopener\">Portal de Gest\u00e3o NFS-e<\/a>&nbsp;e fa\u00e7a o login com o n\u00famero de CNPJ e senha.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_%E2%80%93_Apos_o_login_clique_em_%E2%80%9CNFS-e_Emitidas%E2%80%9D_no_canto_superior_direito\"><\/span>2 &#8211; Ap\u00f3s o login, clique em \u201c<strong>NFS-e Emitidas<\/strong>\u201d, no canto superior direito.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" alt=\"cancelar-nfse.png\" height=\"191\" src=\"https:\/\/i0.wp.com\/cdn.companyhero.com\/static\/images\/cancelar-nfse.width-800.png?resize=800%2C191&#038;ssl=1\" width=\"800\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_%E2%80%93_Clique_nas_tres_bolinhas_referentes_a_nota_fiscal_que_voce_deseja_cancelar_no_canto_direito_da_tela\"><\/span>3 &#8211; Clique nas tr\u00eas bolinhas referentes a nota fiscal que voc\u00ea deseja cancelar, no canto direito da tela.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"cancelar-nfse-2.png\" height=\"126\" src=\"https:\/\/i0.wp.com\/cdn.companyhero.com\/static\/images\/cancelar-nfse-2.width-800.png?resize=800%2C126&#038;ssl=1\" width=\"800\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_%E2%80%93_Em_seguida_clique_em_%E2%80%9CCancelar_NFS-e%E2%80%9D\"><\/span>4 &#8211; Em seguida, clique em \u201cCancelar NFS-e\u201d.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_%E2%80%93_Selecione_a_opcao_referente_ao_motivo_do_cancelamento_e_descreva_a_justificativa\"><\/span>5 &#8211; Selecione a op\u00e7\u00e3o referente ao motivo do cancelamento e descreva a justificativa.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_%E2%80%93_Pronto_a_confirmacao_do_cancelamento_ira_aparecer_na_tela\"><\/span>6 &#8211; Pronto, a confirma\u00e7\u00e3o do cancelamento ir\u00e1 aparecer na tela.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>\u26a0\ufe0f <strong>1 em cada 3 MEIs possui pend\u00eancias no CNPJ<\/strong> \u2014 e voc\u00ea pode ser um, sem saber. <a href=\"https:\/\/go.companyhero.com\/blog-plano-mei-otimizado-tipo-2\" target=\"_blank\" rel=\"noopener\"><strong>Descubra se tem pend\u00eancias e regularize seu MEI por menos de R$1\/dia<\/strong><\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/go.companyhero.com\/blog-plano-mei-otimizado-tipo-2\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"267\" src=\"https:\/\/i0.wp.com\/www.companyhero.com\/blog\/wp-content\/uploads\/2025\/03\/Banners-BLOG-otimizacaoBanner-Plano-Mei-Hero-Post-Blog_2.jpg?resize=800%2C267&#038;ssl=1\" alt=\"\" class=\"wp-image-3501\" srcset=\"https:\/\/i0.wp.com\/www.companyhero.com\/blog\/wp-content\/uploads\/2025\/03\/Banners-BLOG-otimizacaoBanner-Plano-Mei-Hero-Post-Blog_2.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.companyhero.com\/blog\/wp-content\/uploads\/2025\/03\/Banners-BLOG-otimizacaoBanner-Plano-Mei-Hero-Post-Blog_2.jpg?resize=300%2C100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.companyhero.com\/blog\/wp-content\/uploads\/2025\/03\/Banners-BLOG-otimizacaoBanner-Plano-Mei-Hero-Post-Blog_2.jpg?resize=1024%2C341&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.companyhero.com\/blog\/wp-content\/uploads\/2025\/03\/Banners-BLOG-otimizacaoBanner-Plano-Mei-Hero-Post-Blog_2.jpg?resize=768%2C256&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p><a id=\"\" href=\"https:\/\/go.companyhero.com\/43ara\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cancelar nota fiscal sendo microempreendedor individual \u00e9 um processo r\u00e1pido e feito pela internet. Aprenda agora!<\/p>\n","protected":false},"author":2,"featured_media":1241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-1237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-cnpj"],"_links":{"self":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts\/1237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/comments?post=1237"}],"version-history":[{"count":6,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts\/1237\/revisions"}],"predecessor-version":[{"id":3508,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/posts\/1237\/revisions\/3508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/media\/1241"}],"wp:attachment":[{"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/media?parent=1237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/categories?post=1237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.companyhero.com\/blog\/wp-json\/wp\/v2\/tags?post=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}